{"id":1,"count":21,"description":"","link":"https:\/\/tick.blue\/blog\/category\/tutorials\/","name":"Tutorials","slug":"tutorials","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/tick.blue\/blog\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tick.blue\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tick.blue\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tick.blue\/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}